{"id":2487,"date":"2015-04-01T13:21:36","date_gmt":"2015-04-01T11:21:36","guid":{"rendered":"http:\/\/www.psychee.org\/blog\/?p=2487"},"modified":"2015-04-01T13:21:36","modified_gmt":"2015-04-01T11:21:36","slug":"offre-speciale-20-premier-projet-auteurs-et-createurs-jdr","status":"publish","type":"post","link":"http:\/\/www.psychee.org\/blog\/offre-speciale-20-premier-projet-auteurs-et-createurs-jdr\/","title":{"rendered":"Offre sp\u00e9ciale -20% premier projet auteurs, et cr\u00e9ateurs JDR"},"content":{"rendered":"<p style=\"text-align: justify;\">Et non, ceci n&rsquo;est pas un poisson d&rsquo;Avril, par contre l&rsquo;offre est limit\u00e9 pour un an, alors profitez-en !<br \/>\n<em>(cliquez sur l&rsquo;image pour l&rsquo;afficher, et une seconde fois pour l&rsquo;avoir en taille r\u00e9elle)<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2489\" data-permalink=\"http:\/\/www.psychee.org\/blog\/offre-speciale-20-premier-projet-auteurs-et-createurs-jdr\/promo\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg?fit=800%2C5295\" data-orig-size=\"800,5295\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"promo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg?fit=121%2C800\" class=\"alignnone wp-image-2489 size-full\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg?resize=800%2C5295\" alt=\"promo\" width=\"800\" height=\"5295\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg?w=800 800w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg?resize=44%2C290 44w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo.jpg?resize=121%2C800 121w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et non, ceci n&rsquo;est pas un poisson d&rsquo;Avril, par contre l&rsquo;offre est limit\u00e9 pour un an, alors profitez-en ! (cliquez<\/p>\n","protected":false},"author":52,"featured_media":2491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,11],"tags":[329,133,242,20,330,402,54,15,328,331,119,150,18],"class_list":["post-2487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-illustrations","category-blog","tag-329","tag-axelle","tag-bouet","tag-commande","tag-debutants","tag-couleur","tag-illustrations-noir-et-blanc","tag-jeux-de-roles","tag-offre-speciale","tag-premier-projet","tag-psychee","tag-roman","tag-travail"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2iISD-E7","jetpack-related-posts":[{"id":4076,"url":"http:\/\/www.psychee.org\/blog\/les-illustrations-pour-heritages\/","url_meta":{"origin":2487,"position":0},"title":"Les illustrations pour H\u00e9ritages","author":"axelle Bouet","date":"31 mai 2017","format":false,"excerpt":"Comme je le mentionne sur l'article qui lui est consacr\u00e9, H\u00e9ritages est un projet de roman illustr\u00e9 mais c'est aussi l'id\u00e9e \u00e9ventuelle d'un projet de bande dessin\u00e9e -un jour, peut-\u00eatre, allez savoir ? Bref, je dessine pas mal \u00e0 ce sujet et je tenais \u00e0 vous partager mes illustrations pr\u00e9f\u00e9r\u00e9es\u2026","rel":"","context":"Dans &quot;H\u00e9ritages&quot;","block_context":{"text":"H\u00e9ritages","link":"http:\/\/www.psychee.org\/blog\/category\/autres-creations\/heritages\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/logo3.jpg?fit=1100%2C580&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/logo3.jpg?fit=1100%2C580&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/logo3.jpg?fit=1100%2C580&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/logo3.jpg?fit=1100%2C580&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/logo3.jpg?fit=1100%2C580&resize=1050%2C600 3x"},"classes":[]},{"id":3823,"url":"http:\/\/www.psychee.org\/blog\/pas-beaucoup-de-dessin-recemment-mais-tout-est-relatif\/","url_meta":{"origin":2487,"position":1},"title":"Pas beaucoup de dessin r\u00e9cemment mais tout est relatif.","author":"axelle Bouet","date":"10 d\u00e9cembre 2016","format":false,"excerpt":"Et donc, parce que je ne vais pas trop m'attarder on vous montre les derniers r\u00e9alis\u00e9s. C'est vrai que je dessine moins que je voudrais, mais imp\u00e9ratifs pour mon boulot sur le jeu de r\u00f4le Les Chants de Loss, et soucis de sant\u00e9... et une sciatique et une table \u00e0\u2026","rel":"","context":"Dans &quot;Etudes Erdorin&quot;","block_context":{"text":"Etudes Erdorin","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/erdorin\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/12\/caranaval-final.jpg?fit=1200%2C726&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/12\/caranaval-final.jpg?fit=1200%2C726&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/12\/caranaval-final.jpg?fit=1200%2C726&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/12\/caranaval-final.jpg?fit=1200%2C726&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/12\/caranaval-final.jpg?fit=1200%2C726&resize=1050%2C600 3x"},"classes":[]},{"id":3875,"url":"http:\/\/www.psychee.org\/blog\/princess-sword-woman\/","url_meta":{"origin":2487,"position":2},"title":"Princess Sword-Woman","author":"axelle Bouet","date":"7 f\u00e9vrier 2017","format":false,"excerpt":"Une illustration pour les Chants de Loss, le jeu de r\u00f4le : une des l\u00e9gendes de Loss. Je dois beaucoup \u00e0 Pierre le Pivain pour la r\u00e9ussite de la couleur, gr\u00e2ce \u00e0 ses conseils. Et oui, \u00e7a bosse, mais je suis un peu surcharg\u00e9 en ce moment, c'est pour cela\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/princesse-guerriere-final.jpg?fit=849%2C1200&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/princesse-guerriere-final.jpg?fit=849%2C1200&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/princesse-guerriere-final.jpg?fit=849%2C1200&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/princesse-guerriere-final.jpg?fit=849%2C1200&resize=700%2C400 2x"},"classes":[]},{"id":5953,"url":"http:\/\/www.psychee.org\/blog\/les-heros-de-loss-style-art-nouveau\/","url_meta":{"origin":2487,"position":3},"title":"Les h\u00e9ros de Loss, style Art Nouveau","author":"axelle Bouet","date":"6 f\u00e9vrier 2020","format":false,"excerpt":"Au tout d\u00e9part, une sorte de pari, que j'ai racont\u00e9 sur cet article, l'id\u00e9e a fait son chemin pour devenir un projet d'illustrations. D'une part pour des marques-pages, que vous pourrez voir plus bas, d'autre part pour une future s\u00e9rie deluxe des romans Les Chants de Loss, quand le 4\u00e8me\u2026","rel":"","context":"Dans &quot;Illustrations&quot;","block_context":{"text":"Illustrations","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=1050%2C600 3x"},"classes":[]},{"id":3636,"url":"http:\/\/www.psychee.org\/blog\/15-jours-de-dessins-et-des-illustrations-pour-loss\/","url_meta":{"origin":2487,"position":4},"title":"15 jours de dessins et des illustrations pour Loss","author":"axelle Bouet","date":"17 octobre 2016","format":false,"excerpt":"Depuis le d\u00e9but du mois, je suis tr\u00e8s occup\u00e9e entre la relecture et la correction du tome 2 des Chants de Loss, le travail de r\u00e9daction du jeu de r\u00f4le les Chants de Loss qui arrive inexorablement \u00e0 son terme, et les commandes de mes clients entre deux m\u00e9saventures idiotes\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/10\/moon-bandeau.jpg?fit=1100%2C807&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/10\/moon-bandeau.jpg?fit=1100%2C807&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/10\/moon-bandeau.jpg?fit=1100%2C807&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/10\/moon-bandeau.jpg?fit=1100%2C807&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/10\/moon-bandeau.jpg?fit=1100%2C807&resize=1050%2C600 3x"},"classes":[]},{"id":2538,"url":"http:\/\/www.psychee.org\/blog\/le-projet-concours-dessinez-vos-chants-de-loss\/","url_meta":{"origin":2487,"position":5},"title":"Le projet-Concours : dessinez vos Chants de Loss","author":"axelle Bouet","date":"4 mai 2015","format":false,"excerpt":"Alors en fait cela se passe sur le blog des Chants de Loss, en attendant l'arriv\u00e9e du site communautaire qui sera r\u00e9alis\u00e9 par les talents et les petits doigts magiques de Yann D\u00e9combaz, Aka BBS, aka la l\u00e9gende r\u00f4liste du Chablais et si vous n'\u00eates ps d'accord je vous tape,\u2026","rel":"","context":"Dans &quot;Links: Jeux de r\u00f4le&quot;","block_context":{"text":"Links: Jeux de r\u00f4le","link":"http:\/\/www.psychee.org\/blog\/category\/jdr\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/jawaad-1.jpg?fit=1200%2C852&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/jawaad-1.jpg?fit=1200%2C852&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/jawaad-1.jpg?fit=1200%2C852&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/jawaad-1.jpg?fit=1200%2C852&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/03\/jawaad-1.jpg?fit=1200%2C852&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/promo2.jpg?fit=1100%2C598","_links":{"self":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/2487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/comments?post=2487"}],"version-history":[{"count":2,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/2487\/revisions"}],"predecessor-version":[{"id":2492,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/2487\/revisions\/2492"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media\/2491"}],"wp:attachment":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media?parent=2487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/categories?post=2487"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/tags?post=2487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}