{"id":3282,"date":"2016-03-24T11:41:50","date_gmt":"2016-03-24T09:41:50","guid":{"rendered":"http:\/\/www.psychee.org\/blog\/?p=3282"},"modified":"2016-03-24T11:41:50","modified_gmt":"2016-03-24T09:41:50","slug":"orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss","status":"publish","type":"post","link":"http:\/\/www.psychee.org\/blog\/orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss\/","title":{"rendered":"Orc&rsquo;id\u00e9e 2 et 3 Avril et le nouveau kit de d\u00e9couverte Les Chants de Loss"},"content":{"rendered":"<p style=\"text-align: justify;\">Hier nous avons donc achev\u00e9 avec Alysia la maquette du nouveau kit de d\u00e9couverte Les Chants de loss dont nous aurons quelques exemplaires pour l<a href=\"http:\/\/www.orcidee.ch\/index.php\/la-convention\" target=\"_blank\">a convention Orc&rsquo;id\u00e9e \u00e0 Lausanne d&rsquo;ici une semaine<\/a>. Et&#8230; celui-ci est disponible gratuitement en PDF sur le site internet <a href=\"http:\/\/www.chantsdeloss.com\" target=\"_blank\">www.chantsdeloss.com<\/a>, ou par le lien direct ici :<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.loss-jdr.psychee.org\/wp-content\/uploads\/2016\/03\/Kit2.0Web3.pdf\" target=\"_blank\">Les Chants de Loss, kit de d\u00e9couverte V2 pour le web, PDF 4 Mo.<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0Il fait 40 page, richement illustr\u00e9 et en couleur, nettement plus a\u00e9r\u00e9 et abordable que le pav\u00e9 indigeste que nous avions r\u00e9alis\u00e9 la premi\u00e8re fois. Entretemps, j&rsquo;ai gagn\u00e9 des XP en \u00ab\u00a0r\u00e9sumer des textes\u00a0\u00bb. La version papier sera trouvable sur nos stands de conventions, et d&rsquo;ici quelques semaines, vous pourrez aussi la commander chez <a href=\"http:\/\/editionsstellamaris.blogspot.ch\/\" target=\"_blank\">Stellamaris<\/a>.<\/p>\n<p style=\"text-align: justify;\">Vous pouvez partager et diffuser \u00e0 loisir le kit, sur vos pages web et r\u00e9seaux sociaux pr\u00e9f\u00e9r\u00e9s, pensez juste \u00e0 cr\u00e9diter les Chants de Loss ou les auteurs, merci !<\/p>\n<p style=\"text-align: justify;\">Et pour le plaisir, quelques-unes des illustrations r\u00e9alis\u00e9s\u00a0 pour le kit et quelques screens de pages pour vous donner envie !<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg\" rel=\"attachment wp-att-3283\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3283\" data-permalink=\"http:\/\/www.psychee.org\/blog\/orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss\/p3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?fit=625%2C881\" data-orig-size=\"625,881\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"p3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?fit=480%2C677\" class=\"alignnone size-large wp-image-3283\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?resize=474%2C669\" alt=\"p3\" width=\"474\" height=\"669\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?resize=480%2C677 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?resize=206%2C290 206w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?resize=341%2C480 341w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p3.jpg?w=625 625w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg\" rel=\"attachment wp-att-3284\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3284\" data-permalink=\"http:\/\/www.psychee.org\/blog\/orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss\/p1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?fit=1253%2C884\" data-orig-size=\"1253,884\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"p1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?fit=480%2C339\" class=\"alignnone size-large wp-image-3284\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?resize=474%2C335\" alt=\"p1\" width=\"474\" height=\"335\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?resize=480%2C339 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?resize=290%2C205 290w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?resize=350%2C247 350w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?resize=768%2C542 768w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/p1.jpg?w=1253 1253w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg\" rel=\"attachment wp-att-3286\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3286\" data-permalink=\"http:\/\/www.psychee.org\/blog\/orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss\/armanth-1100\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?fit=1100%2C778\" data-orig-size=\"1100,778\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"armanth-1100\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?fit=480%2C339\" class=\"alignnone size-large wp-image-3286\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?resize=474%2C335\" alt=\"armanth-1100\" width=\"474\" height=\"335\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?resize=480%2C339 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?resize=290%2C205 290w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?resize=350%2C248 350w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?resize=768%2C543 768w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armanth-1100.jpg?w=1100 1100w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg\" rel=\"attachment wp-att-3287\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3287\" data-permalink=\"http:\/\/www.psychee.org\/blog\/orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss\/anqimenes-1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?fit=1280%2C905\" data-orig-size=\"1280,905\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"anqimenes-1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?fit=480%2C339\" class=\"alignnone size-large wp-image-3287\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?resize=474%2C335\" alt=\"anqimenes-1280\" width=\"474\" height=\"335\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?resize=480%2C339 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?resize=290%2C205 290w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?resize=350%2C247 350w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?resize=768%2C543 768w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/anqimenes-1280.jpg?w=1280 1280w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg\" rel=\"attachment wp-att-3288\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3288\" data-permalink=\"http:\/\/www.psychee.org\/blog\/orcidee-2-et-3-avril-et-le-nouveau-kit-de-decouverte-les-chants-de-loss\/armes-tas4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?fit=1136%2C920\" data-orig-size=\"1136,920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"armes-tas4\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?fit=480%2C389\" class=\"alignnone size-large wp-image-3288\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?resize=474%2C384\" alt=\"armes-tas4\" width=\"474\" height=\"384\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?resize=480%2C389 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?resize=290%2C235 290w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?resize=350%2C283 350w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?resize=768%2C622 768w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/armes-tas4.jpg?w=1136 1136w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier nous avons donc achev\u00e9 avec Alysia la maquette du nouveau kit de d\u00e9couverte Les Chants de loss dont nous<\/p>\n","protected":false},"author":52,"featured_media":3285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,38,149,11],"tags":[342,133,242,343,402,54,335,15,27,472,230,410,316,119,241],"class_list":["post-3282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-couleur","category-jeux-de-role","category-loss","category-blog","tag-alysia-loretan","tag-axelle","tag-bouet","tag-emilie-latieule","tag-couleur","tag-illustrations-noir-et-blanc","tag-jdr","tag-jeux-de-roles","tag-job","tag-kit-decouverte","tag-les-chants-de-loss","tag-loss","tag-orcidee","tag-psychee","tag-stellamaris"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2iISD-QW","jetpack-related-posts":[{"id":3271,"url":"http:\/\/www.psychee.org\/blog\/boulot-boulot-boulot\/","url_meta":{"origin":3282,"position":0},"title":"Boulot, boulot, boulot !","author":"axelle Bouet","date":"15 mars 2016","format":false,"excerpt":"Et pour le plaisir des yeux, un de mes derniers noir&blanc, une illustration pour les Chants de Loss, mais en fait inspir\u00e9e d'une photo d'art qui m'a marqu\u00e9e. Je pensais en faire une bichromie et un fond couleurs, mais je vais devoir reporter cela, car j'ai peu de temps pour\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/flower-bandeau.jpg?fit=1100%2C680&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/flower-bandeau.jpg?fit=1100%2C680&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/flower-bandeau.jpg?fit=1100%2C680&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/flower-bandeau.jpg?fit=1100%2C680&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/flower-bandeau.jpg?fit=1100%2C680&resize=1050%2C600 3x"},"classes":[]},{"id":2522,"url":"http:\/\/www.psychee.org\/blog\/le-stand-les-chants-de-loss-a-orcidee-dans-trois-jours\/","url_meta":{"origin":3282,"position":1},"title":"Le stand Les Chants de Loss \u00e0 Orc&rsquo;id\u00e9e dans trois jours !","author":"axelle Bouet","date":"15 avril 2015","format":false,"excerpt":"Pour rappel dans trois jours, ce Samedi 18 Avril , d\u00e9bute la convention de jeu de r\u00f4le Orc'id\u00e9e\u200b. J'y serai pr\u00e9sente, \u00e0 un stand, avec des exemplaires du roman Les Chants de Loss Livre 1 : Armanth\u200b \u00e0 d\u00e9dicacer, des posters aussi, et des marques-pages, et Samedi soir, \u00e0 18h00\u2026","rel":"","context":"Dans &quot;Jeux de r\u00f4le&quot;","block_context":{"text":"Jeux de r\u00f4le","link":"http:\/\/www.psychee.org\/blog\/category\/non-classe\/jeux-de-role\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/kit-couv-1100.jpg?fit=848%2C1200&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/kit-couv-1100.jpg?fit=848%2C1200&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/kit-couv-1100.jpg?fit=848%2C1200&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/kit-couv-1100.jpg?fit=848%2C1200&resize=700%2C400 2x"},"classes":[]},{"id":6692,"url":"http:\/\/www.psychee.org\/blog\/cest-le-free-rpg-day-plein-de-trucs-gratos-enjoy\/","url_meta":{"origin":3282,"position":2},"title":"C\u2019est le Free RPG Day, plein de trucs gratos, enjoy !","author":"axelle Bouet","date":"24 juin 2023","format":false,"excerpt":"Le Free RPG day, comme son nom l\u2019indique, c\u2019est une journ\u00e9e de promotion du jeu de r\u00f4le o\u00f9 boutiques et auteurs offrent du matos gratos pour mettre \u00e0 l\u2019honneur notre loisir. Et cette ann\u00e9e, pour l\u2019occasion, on vous offre deux-trois trucs \u00e0 d\u00e9couvrir ou red\u00e9couvrir, c\u2019est parti pour la liste\u00a0!\u2026","rel":"","context":"Dans &quot;Divers&quot;","block_context":{"text":"Divers","link":"http:\/\/www.psychee.org\/blog\/category\/autres-creations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2023\/06\/rpg-day.png?fit=1200%2C750&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2023\/06\/rpg-day.png?fit=1200%2C750&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2023\/06\/rpg-day.png?fit=1200%2C750&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2023\/06\/rpg-day.png?fit=1200%2C750&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2023\/06\/rpg-day.png?fit=1200%2C750&resize=1050%2C600 3x"},"classes":[]},{"id":3268,"url":"http:\/\/www.psychee.org\/blog\/le-potcommun-les-chants-de-loss-a-orcidee-et-deja-mille-remerciements\/","url_meta":{"origin":3282,"position":3},"title":"Le PotCommun Les Chants de Loss \u00e0 Orc&rsquo;id\u00e9e, et d\u00e9j\u00e0, mille remerciements !","author":"axelle Bouet","date":"14 mars 2016","format":false,"excerpt":"Merci.... merci de tout mon coeur. Patrick Arbus \u00e0 ce sujet et devant ma surprise me disait : on r\u00e9colte ce qu'on s\u00e8me. Je ne sais pas ce que j'ai sem\u00e9 pour un tel cadeau. Peut-\u00eatre et l\u00e0 pour citer mon Ange : tu les fais r\u00eaver, alors cela a\u2026","rel":"","context":"Dans &quot;Rien \u00e0 voir&quot;","block_context":{"text":"Rien \u00e0 voir","link":"http:\/\/www.psychee.org\/blog\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/bandeau-loss.jpg?fit=851%2C315&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/bandeau-loss.jpg?fit=851%2C315&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/bandeau-loss.jpg?fit=851%2C315&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/bandeau-loss.jpg?fit=851%2C315&resize=700%2C400 2x"},"classes":[]},{"id":2514,"url":"http:\/\/www.psychee.org\/blog\/les-posters-des-chants-de-loss-et-la-boutique-de-loss\/","url_meta":{"origin":3282,"position":4},"title":"Les posters des Chants de Loss, et la boutique de Loss","author":"axelle Bouet","date":"11 avril 2015","format":false,"excerpt":"J'ai eu quelques journ\u00e9es (TRES) occup\u00e9es ces derniers temps, et j'en suis pas encore sortie, mais j'en vois le bout, ha haaa! Je devrais avoir tout de pr\u00eat pour Orc'id\u00e9e, les posters et flyers seront pr\u00eats Mercredi, j'ai la banderole, je vais avoir des cartes de visite, les bouquins fr\u00e9tillent\u2026","rel":"","context":"Dans &quot;Illustrations&quot;","block_context":{"text":"Illustrations","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/anis-color.jpg?fit=848%2C1200&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/anis-color.jpg?fit=848%2C1200&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/anis-color.jpg?fit=848%2C1200&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/04\/anis-color.jpg?fit=848%2C1200&resize=700%2C400 2x"},"classes":[]},{"id":3587,"url":"http:\/\/www.psychee.org\/blog\/les-chants-de-loss-psychee-et-ses-aquarelles-a-octogone-et-autres-nouvelles\/","url_meta":{"origin":3282,"position":5},"title":"Les Chants de Loss, Psych\u00e9e et ses aquarelles \u00e0 OctoG\u00f4ne et autres nouvelles.","author":"axelle Bouet","date":"8 septembre 2016","format":false,"excerpt":"D'ici trois semaines aura lieu la 7\u00e8me Convention OctoG\u00f4ne, du 30 septembre au 2 octobre 2016 Au double Mixte, \u00e0 Villeurbanne, \u00e0 cot\u00e9 de Lyon. Et si vous avez suivi les aventures des Chants de loss, vous devez savoir que toute l\u2019\u00e9quipe, Alysia, Emilie et moi, nous y serons pour\u2026","rel":"","context":"Dans &quot;Illustrations couleurs&quot;","block_context":{"text":"Illustrations couleurs","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/couleur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/09\/banniere4-final.jpg?fit=1185%2C792&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/09\/banniere4-final.jpg?fit=1185%2C792&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/09\/banniere4-final.jpg?fit=1185%2C792&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/09\/banniere4-final.jpg?fit=1185%2C792&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/09\/banniere4-final.jpg?fit=1185%2C792&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/03\/double-page-kit.jpg?fit=1249%2C885","_links":{"self":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/3282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/comments?post=3282"}],"version-history":[{"count":1,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/3282\/revisions"}],"predecessor-version":[{"id":3290,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/3282\/revisions\/3290"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media\/3285"}],"wp:attachment":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media?parent=3282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/categories?post=3282"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/tags?post=3282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}