{"id":3889,"date":"2017-02-09T13:31:07","date_gmt":"2017-02-09T11:31:07","guid":{"rendered":"http:\/\/www.psychee.org\/blog\/?p=3889"},"modified":"2017-02-09T13:31:07","modified_gmt":"2017-02-09T11:31:07","slug":"le-champion-du-trone-de-rubis","status":"publish","type":"post","link":"http:\/\/www.psychee.org\/blog\/le-champion-du-trone-de-rubis\/","title":{"rendered":"Le Champion du Tr\u00f4ne de Rubis"},"content":{"rendered":"<p>C&rsquo;est la premi\u00e8re fois que je tente de faire une peinture de personnage en armure avec un brin de compo et de mise en sc\u00e8ne,\u00a0 et cela se voit. J&rsquo;entends par l\u00e0 que le r\u00e9sultat fait le job voulu, mais que je suis encore loin du r\u00e9sultat que je vise et j&rsquo;approche \u00e0 pas lents.<\/p>\n<p>Le truc, c&rsquo;est que la peinture est loin d&rsquo;\u00eatre du dessin et de la colo de qualit\u00e9, ce n&rsquo;est pas du tout la m\u00eame technique : c&rsquo;est nettement plus rude\u00a0 m\u00eame si certains trucs sont communs. C&rsquo;est un travail que je fais peu et la plupart du temps, je me plante en cour de route et vous ne voyez jamais le r\u00e9sultat. Comme une des mes principales pr\u00e9occupations est d&rsquo;obtenir le meilleur r\u00e9sultat possible en un minimum de temps, j&rsquo;ai souvent travaill\u00e9 et rat\u00e9 des speedpaintings, avec mod\u00e8les ou pas,\u00a0 que vous ne verrez jamais, me refusant \u00e0 passer 20 ou 30 heures sur une peinture quand j&rsquo;estime que le r\u00e9sultat ne vaudra pas le temps consacr\u00e9. Bha oui, j&rsquo;ai juste pas le temps, bosser vite est n\u00e9cessaire pour gagner un peu ma vie et c&rsquo;est pas comme si j&rsquo;avais pas un tome 3 de mes romans \u00e0 \u00e9crire, et un jeu de r\u00f4le \u00e0 finir pour Mars-Avril !<\/p>\n<p>Maintenant, cela commence \u00e0 venir, \u00e0 force de travail. Ici, l&rsquo;illustration a pris un peu plus de sept heures ; elle est imparfaite et d&rsquo;ailleurs <a href=\"https:\/\/www.lepixx.eu\/\" target=\"_blank\">Pierre le Pivain<\/a> me dit que y&rsquo;a vraiment des choses \u00e0 retravailler dessus. Mais m\u00eame perfectible, elle obtient le r\u00e9sultat vis\u00e9 : mettre en sc\u00e8ne avec une qualit\u00e9 et une ambiance qui me font plaisir un personnage embl\u00e9matique du jeu de r\u00f4le les Chants de Loss, et \u00e0 titre personnel, me permettre de progresser. Pour avoir un bon niveau de peinture, il me faudra encore toute cette ann\u00e9e. C&rsquo;est l&rsquo;objectif. Alors&#8230;. au travail et enjoy !<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3890\" data-permalink=\"http:\/\/www.psychee.org\/blog\/le-champion-du-trone-de-rubis\/champion-final3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?fit=1280%2C1810\" data-orig-size=\"1280,1810\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"champion-final3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?fit=480%2C679\" class=\"alignnone size-large wp-image-3890\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?resize=474%2C671\" alt=\"\" width=\"474\" height=\"671\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?resize=480%2C679 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?resize=205%2C290 205w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?resize=339%2C480 339w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/champion-final3.jpg?w=1280 1280w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est la premi\u00e8re fois que je tente de faire une peinture de personnage en armure avec un brin de compo<\/p>\n","protected":false},"author":52,"featured_media":3891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,6,9,149,11],"tags":[133,242,402,15,27,230,410,119,18],"class_list":["post-3889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-illustrations","category-couleur","category-jobs","category-loss","category-blog","tag-axelle","tag-bouet","tag-couleur","tag-jeux-de-roles","tag-job","tag-les-chants-de-loss","tag-loss","tag-psychee","tag-travail"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/02\/bandeau-champion.jpg?fit=1100%2C639","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2iISD-10J","jetpack-related-posts":[{"id":914,"url":"http:\/\/www.psychee.org\/blog\/schoolmage-bientot-termine\/","url_meta":{"origin":3889,"position":0},"title":"Schoolmage, bient\u00f4t termin\u00e9","author":"Psychee","date":"18 avril 2013","format":false,"excerpt":"On commence \u00e0 voir o\u00f9 je voulais en venir avec le dessin, j'ai encore des doutes sur le traitement des\u00a0lumi\u00e8res, m\u00eame en aplat, surtout pour le dragon, qui finalement a une couleur qui me\u00a0d\u00e9pla\u00eet, mais je m'attendais \u00e0 devoir revenir dessus, et le fond se d\u00e9taille, sachant que je le\u2026","rel":"","context":"Dans &quot;Illustrations couleurs&quot;","block_context":{"text":"Illustrations couleurs","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/couleur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2013\/04\/schoolmage3.jpg?fit=1200%2C848&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2013\/04\/schoolmage3.jpg?fit=1200%2C848&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2013\/04\/schoolmage3.jpg?fit=1200%2C848&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2013\/04\/schoolmage3.jpg?fit=1200%2C848&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2013\/04\/schoolmage3.jpg?fit=1200%2C848&resize=1050%2C600 3x"},"classes":[]},{"id":2972,"url":"http:\/\/www.psychee.org\/blog\/automn-cest-de-saison\/","url_meta":{"origin":3889,"position":1},"title":"Automn, c&rsquo;est de saison","author":"axelle Bouet","date":"3 octobre 2015","format":false,"excerpt":"Entam\u00e9 cet \u00e9t\u00e9 puis d\u00e9laiss\u00e9 pour diverses raisons allant de taff urgent en passant par \u00e0 force je l'avais oubli\u00e9, j'ai finis cette peinture : \"Automn\" un portrait de Lisa et Jawaad, les deux protagonistes du roman les Chants de Loss. Oui, d'ici le tome 4 on pourra les voir\u2026","rel":"","context":"Dans &quot;Illustrations&quot;","block_context":{"text":"Illustrations","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/10\/automn-bandeau.jpg?fit=1100%2C730&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/10\/automn-bandeau.jpg?fit=1100%2C730&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/10\/automn-bandeau.jpg?fit=1100%2C730&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/10\/automn-bandeau.jpg?fit=1100%2C730&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/10\/automn-bandeau.jpg?fit=1100%2C730&resize=1050%2C600 3x"},"classes":[]},{"id":5953,"url":"http:\/\/www.psychee.org\/blog\/les-heros-de-loss-style-art-nouveau\/","url_meta":{"origin":3889,"position":2},"title":"Les h\u00e9ros de Loss, style Art Nouveau","author":"axelle Bouet","date":"6 f\u00e9vrier 2020","format":false,"excerpt":"Au tout d\u00e9part, une sorte de pari, que j'ai racont\u00e9 sur cet article, l'id\u00e9e a fait son chemin pour devenir un projet d'illustrations. D'une part pour des marques-pages, que vous pourrez voir plus bas, d'autre part pour une future s\u00e9rie deluxe des romans Les Chants de Loss, quand le 4\u00e8me\u2026","rel":"","context":"Dans &quot;Illustrations&quot;","block_context":{"text":"Illustrations","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/trio-affiche-bandeau.png?fit=1200%2C579&resize=1050%2C600 3x"},"classes":[]},{"id":3800,"url":"http:\/\/www.psychee.org\/blog\/semaine-difficile-et-de-nouveaux-progres-en-colo\/","url_meta":{"origin":3889,"position":3},"title":"Semaine difficile et de nouveaux progr\u00e8s en colo","author":"axelle Bouet","date":"25 novembre 2016","format":false,"excerpt":"Bon, je ne peint toujours pas encore, parce que je n'ose pas encore, mais va bien falloir que je m'y remette. Mais c'est un peu compliqu\u00e9 : je r\u00e9apprends \u00e0 dessiner, ce qui implique de choisir quelles priorit\u00e9s donner \u00e0 mes temps et efforts d'\u00e9tude. Pour le moment, c'est surtout\u2026","rel":"","context":"Dans &quot;Etudes Erdorin&quot;","block_context":{"text":"Etudes Erdorin","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/erdorin\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/etude-inithil-bandeau.jpg?fit=1200%2C501&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/etude-inithil-bandeau.jpg?fit=1200%2C501&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/etude-inithil-bandeau.jpg?fit=1200%2C501&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/etude-inithil-bandeau.jpg?fit=1200%2C501&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/etude-inithil-bandeau.jpg?fit=1200%2C501&resize=1050%2C600 3x"},"classes":[]},{"id":3957,"url":"http:\/\/www.psychee.org\/blog\/un-cadeau-pour-les-fans-des-chants-de-loss\/","url_meta":{"origin":3889,"position":4},"title":"Un cadeau pour les fans des Chants de Loss","author":"axelle Bouet","date":"25 avril 2017","format":false,"excerpt":"Voici un portait au format fond d'\u00e9cran large, de Lisa, protagoniste principale des Chants de Loss. A la base, j'ai fais cette peinture comme test de niveau et pour me remonter le moral. Le d\u00e9cor a chang\u00e9 six fois, n'a rien \u00e0 voir avec ce que j'avais en t\u00eate, mais\u2026","rel":"","context":"Dans &quot;Illustrations&quot;","block_context":{"text":"Illustrations","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/04\/lisa-paravent13.jpg?fit=1200%2C672&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/04\/lisa-paravent13.jpg?fit=1200%2C672&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/04\/lisa-paravent13.jpg?fit=1200%2C672&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/04\/lisa-paravent13.jpg?fit=1200%2C672&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2017\/04\/lisa-paravent13.jpg?fit=1200%2C672&resize=1050%2C600 3x"},"classes":[]},{"id":3320,"url":"http:\/\/www.psychee.org\/blog\/a-travers-espace-et-temps\/","url_meta":{"origin":3889,"position":5},"title":"A travers espace et temps.","author":"axelle Bouet","date":"14 avril 2016","format":false,"excerpt":"C'est le titre de cette illustration qui en fait va de pair avec le futur chapitre 14 du roman Les Chants de Loss... que je pensais fini hier... sauf que. J'ai fais la maladroite, et depuis deux jours j'ai la main gauche qui pose quelques soucis, le temps que ma\u2026","rel":"","context":"Dans &quot;Illustrations couleurs&quot;","block_context":{"text":"Illustrations couleurs","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/couleur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/04\/lisa-orchys-final-bandeau.jpg?fit=1100%2C578&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/04\/lisa-orchys-final-bandeau.jpg?fit=1100%2C578&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/04\/lisa-orchys-final-bandeau.jpg?fit=1100%2C578&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/04\/lisa-orchys-final-bandeau.jpg?fit=1100%2C578&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/04\/lisa-orchys-final-bandeau.jpg?fit=1100%2C578&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/3889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/comments?post=3889"}],"version-history":[{"count":1,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/3889\/revisions"}],"predecessor-version":[{"id":3892,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/3889\/revisions\/3892"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media\/3891"}],"wp:attachment":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media?parent=3889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/categories?post=3889"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/tags?post=3889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}