{"id":5918,"date":"2020-01-24T11:36:44","date_gmt":"2020-01-24T09:36:44","guid":{"rendered":"http:\/\/www.psychee.org\/blog\/?p=5918"},"modified":"2020-01-24T11:36:44","modified_gmt":"2020-01-24T09:36:44","slug":"quelques-portraits-de-personnages","status":"publish","type":"post","link":"http:\/\/www.psychee.org\/blog\/quelques-portraits-de-personnages\/","title":{"rendered":"Quelques portraits de personnages"},"content":{"rendered":"<p>Et ils furent accueillis avec joie, ces portraits \u00e0 faire, une commande pour le jeu de r\u00f4le <a href=\"https:\/\/www.facebook.com\/ynnpryddein\" target=\"_blank\" rel=\"noopener noreferrer\">Ynn Pryddein<\/a>. Simples, sans exigences ardues, ils m&rsquo;ont permis de reprendre le crayon et d\u00e9poussi\u00e9rer un talent d&rsquo;illustratrice laiss\u00e9 de cot\u00e9 durant ma grosse d\u00e9prime depuis Octobre. Je dois encore en faire quatre, ce qui devrait \u00eatre fait ce week-end ou Lundi, si les crises de migraines veulent bien me foutre la paix.<\/p>\n<p>Mais c&rsquo;est un plaisir de vous annoncer que je rebosse enfin, et me remets au dessin en vous montrant ce travail ! J&rsquo;avance aussi, j&rsquo;ai bient\u00f4t fini, le tome 3 des Chants de Loss, mais je vous en reparlerais une prochaine fois.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5920\" data-permalink=\"http:\/\/www.psychee.org\/blog\/quelques-portraits-de-personnages\/portraits\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?fit=1810%2C1280\" data-orig-size=\"1810,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"portraits\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?fit=480%2C339\" class=\"alignnone wp-image-5920 size-full\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?resize=800%2C566\" alt=\"\" width=\"800\" height=\"566\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?w=1810 1810w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?resize=350%2C248 350w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?resize=480%2C339 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?resize=290%2C205 290w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?resize=1536%2C1086 1536w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5919\" data-permalink=\"http:\/\/www.psychee.org\/blog\/quelques-portraits-de-personnages\/portraits2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?fit=1810%2C1280\" data-orig-size=\"1810,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"portraits2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?fit=480%2C339\" class=\"alignnone wp-image-5919 size-full\" src=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?resize=800%2C566\" alt=\"\" width=\"800\" height=\"566\" srcset=\"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?w=1810 1810w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?resize=350%2C248 350w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?resize=480%2C339 480w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?resize=290%2C205 290w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?resize=1536%2C1086 1536w, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et ils furent accueillis avec joie, ces portraits \u00e0 faire, une commande pour le jeu de r\u00f4le Ynn Pryddein. Simples,<\/p>\n","protected":false},"author":52,"featured_media":5919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[615,5,3,38,11],"tags":[133,242,54,15,418,244,119,18,391],"class_list":["post-5918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-commissions","category-noir","category-illustrations","category-jeux-de-role","category-blog","tag-axelle","tag-bouet","tag-illustrations-noir-et-blanc","tag-jeux-de-roles","tag-personnages","tag-portraits","tag-psychee","tag-travail","tag-ynn-pryddein"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/01\/portraits2.png?fit=1810%2C1280","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2iISD-1xs","jetpack-related-posts":[{"id":6203,"url":"http:\/\/www.psychee.org\/blog\/il-y-avait-longtemps\/","url_meta":{"origin":5918,"position":0},"title":"Il y avait longtemps&#8230;","author":"axelle Bouet","date":"27 avril 2021","format":false,"excerpt":"Une tendinite qui a longuement dur\u00e9, des soucis de sant\u00e9, les cons\u00e9quences morales et sociales du confinement du au COVID-19 et un peu de malchance... bref, je suis rest\u00e9 un long moment sans produire (plus de quatre mois). Je ne suis pas rest\u00e9 sans rien faire, mais ce ne fut\u2026","rel":"","context":"Dans &quot;Commissions&quot;","block_context":{"text":"Commissions","link":"http:\/\/www.psychee.org\/blog\/category\/commissions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2021\/04\/Sans-titre-1.jpg?fit=1200%2C750&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2021\/04\/Sans-titre-1.jpg?fit=1200%2C750&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2021\/04\/Sans-titre-1.jpg?fit=1200%2C750&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2021\/04\/Sans-titre-1.jpg?fit=1200%2C750&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2021\/04\/Sans-titre-1.jpg?fit=1200%2C750&resize=1050%2C600 3x"},"classes":[]},{"id":2827,"url":"http:\/\/www.psychee.org\/blog\/un-dessin-par-jour-si-si-mais-en-un-tas\/","url_meta":{"origin":5918,"position":1},"title":"Un dessin par jour, si si&#8230; mais en un tas !","author":"axelle Bouet","date":"17 juillet 2015","format":false,"excerpt":"Je bosse pas mal ces temps, et quand je ne bosse pas, j\u2019accueille quelques jours ma ch\u00e8re amie Emilie Latieule \u00e0 la maison. Donc, moins de temps pour le blog, je n'ai entre autres pas pu prendre le temps de faire le second cours d'initiation au dessin, ni de poursuivre\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/07\/elfe-bandeau.jpg?fit=1100%2C678&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/07\/elfe-bandeau.jpg?fit=1100%2C678&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/07\/elfe-bandeau.jpg?fit=1100%2C678&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/07\/elfe-bandeau.jpg?fit=1100%2C678&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2015\/07\/elfe-bandeau.jpg?fit=1100%2C678&resize=1050%2C600 3x"},"classes":[]},{"id":6544,"url":"http:\/\/www.psychee.org\/blog\/ynn-pryddein-jdr-en-images\/","url_meta":{"origin":5918,"position":2},"title":"Ynn Pryddein JDR en images","author":"axelle Bouet","date":"26 juillet 2022","format":false,"excerpt":"Ouf, et un gros boulot de fini ! Ce qui n'est pas dommage, car ce boulot \u00e9tait devenu pour moi le symbole maudit de mon retard perp\u00e9tuel en mati\u00e8re de travail, retard cons\u00e9cutif \u00e0 l'accumulation de mes ennuis de sant\u00e9, je reviendrais l\u00e0 dessus. Mais bref, un travail achev\u00e9, et\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/07\/titre.jpg?fit=1200%2C750&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/07\/titre.jpg?fit=1200%2C750&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/07\/titre.jpg?fit=1200%2C750&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/07\/titre.jpg?fit=1200%2C750&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/07\/titre.jpg?fit=1200%2C750&resize=1050%2C600 3x"},"classes":[]},{"id":6443,"url":"http:\/\/www.psychee.org\/blog\/ca-faisait-longtemps-que-javais-pas-fait-un-sujet-a-dessins-partie-1\/","url_meta":{"origin":5918,"position":3},"title":"\u00c7a faisait longtemps que j&rsquo;avais pas fait un sujet \u00e0 dessins, partie 1","author":"axelle Bouet","date":"25 mars 2022","format":false,"excerpt":"... et je parie que cela vous a manqu\u00e9, donc, hop. J'en profite, entre deux dafalgans et des recherches de sources pour mon travail actuel sur le jeu de r\u00f4le Ynn Pryddein, pour lequel je suis en train de faire la majorit\u00e9 des illustrations. D'ailleurs, vous allez voir principalement cela,\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/03\/blog1.jpg?fit=1200%2C750&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/03\/blog1.jpg?fit=1200%2C750&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/03\/blog1.jpg?fit=1200%2C750&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/03\/blog1.jpg?fit=1200%2C750&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2022\/03\/blog1.jpg?fit=1200%2C750&resize=1050%2C600 3x"},"classes":[]},{"id":3666,"url":"http:\/\/www.psychee.org\/blog\/ca-dessine-toujours\/","url_meta":{"origin":5918,"position":4},"title":"\u00c7a dessine toujours !","author":"axelle Bouet","date":"4 novembre 2016","format":false,"excerpt":"Apr\u00e8s avoir fini mes commandes pour les particuliers -d'ailleurs, si vous voulez un dessin de votre personnage de JDR, je peux en faire, et voici le lien vers mes tarifs- je retourne aux commandes d'illustrations de jeu de r\u00f4le, d'une part pour Ynn Pryddein, jeu de r\u00f4le celtique, d'autres part\u2026","rel":"","context":"Dans &quot;Illos noir &amp; blanc&quot;","block_context":{"text":"Illos noir &amp; blanc","link":"http:\/\/www.psychee.org\/blog\/category\/illustrations\/noir\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/mage-bandeau.jpg?fit=1100%2C718&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/mage-bandeau.jpg?fit=1100%2C718&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/mage-bandeau.jpg?fit=1100%2C718&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/mage-bandeau.jpg?fit=1100%2C718&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2016\/11\/mage-bandeau.jpg?fit=1100%2C718&resize=1050%2C600 3x"},"classes":[]},{"id":5989,"url":"http:\/\/www.psychee.org\/blog\/un-doodle-de-6-minutes-en-video\/","url_meta":{"origin":5918,"position":5},"title":"Un doodle de 6 minutes en vid\u00e9o","author":"axelle Bouet","date":"19 f\u00e9vrier 2020","format":false,"excerpt":"Pendant que je patiente, le bras droit band\u00e9 et en \u00e9charpe pour soigner une tendinite du dessinateur, ce qui veut dire que, au moins pour le reste de la semaine, je ne pourrais pas bosser ni user de mon bras droit, je tente de m'occuper... et pour aujourd'hui, en attendant\u2026","rel":"","context":"Dans &quot;Commissions&quot;","block_context":{"text":"Commissions","link":"http:\/\/www.psychee.org\/blog\/category\/commissions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/bors-ynn-pryddein.png?fit=1200%2C848&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/bors-ynn-pryddein.png?fit=1200%2C848&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/bors-ynn-pryddein.png?fit=1200%2C848&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/bors-ynn-pryddein.png?fit=1200%2C848&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.psychee.org\/blog\/wp-content\/uploads\/2020\/02\/bors-ynn-pryddein.png?fit=1200%2C848&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/5918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/comments?post=5918"}],"version-history":[{"count":1,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/5918\/revisions"}],"predecessor-version":[{"id":5921,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/posts\/5918\/revisions\/5921"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media\/5919"}],"wp:attachment":[{"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/media?parent=5918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/categories?post=5918"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.psychee.org\/blog\/wp-json\/wp\/v2\/tags?post=5918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}